{"id":506,"date":"2020-07-23T17:03:22","date_gmt":"2020-07-23T15:03:22","guid":{"rendered":"https:\/\/www.amahotel.fr\/?page_id=506"},"modified":"2025-12-13T16:22:17","modified_gmt":"2025-12-13T15:22:17","slug":"habitacion-confort","status":"publish","type":"page","link":"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/","title":{"rendered":"Habitacion Confort"},"content":{"rendered":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#1c3621&#8243; bg_image=\u00bb80&#8243; bg_position=\u00bbright bottom\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb200&#8243; bottom_padding=\u00bb100&#8243; text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb class=\u00bbheader-inner\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][image_with_animation image_url=\u00bb109&#8243; image_size=\u00bbfull\u00bb max_width=\u00bb100%\u00bb max_width_mobile=\u00bbdefault\u00bb animation_type=\u00bbentrance\u00bb animation=\u00bbNone\u00bb animation_movement_type=\u00bbtransform_y\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bb\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb el_class=\u00bbmain-img-ch\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_custom_heading text=\u00bbHabitaci\u00f3n CONFORT\u00bb font_container=\u00bbtag:h2|font_size:55px|text_align:left|color:%23ffffff|line_height:65px\u00bb use_theme_fonts=\u00bbyes\u00bb css=\u00bb.vc_custom_1595516462463{padding-top: 75px !important;}\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#f2f2f2&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb50&#8243; bottom_padding=\u00bb175&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_raw_html css=\u00bb\u00bb]JTNDYnV0dG9uJTIwY2xhc3MlM0QlMjJnby1zZWpvdXIlMjIlM0UlM0NhJTIwaHJlZiUzRCUyMiUyRmVzJTJGcmVzZXJ2YSUyRiUyMiUyMHN0eWxlJTNEJTIyY29sb3IlM0ElMjNmZmZmZmYlM0IlMjIlM0VSZXNlcnZhJTIwZXN0ZSUyMGhhYml0YWNpJUMzJUIzbiUzQyUyRmElM0UlM0MlMkZidXR0b24lM0U=[\/vc_raw_html][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h3>20 m2 para un descanso relajante<\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bottom_padding=\u00bb25&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#ffffff\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#1c3621&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbAccent-Color\u00bb icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-Croissant\u00bb icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Bandeja de cortes\u00eda \/ Hervidora<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#ffffff\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#1c3621&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbAccent-Color\u00bb icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-Monitor-4&#8243; icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><strong>TV de pantalla plana<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#ffffff\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#1c3621&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbAccent-Color\u00bb icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-Safe-Box\u00bb icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Caja fuerte<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#ffffff\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#1c3621&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbAccent-Color\u00bb icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-Wind-Turbine\u00bb icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Aire acondicionado individual<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#ffffff\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#1c3621&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbAccent-Color\u00bb icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-Phone-Wifi\u00bb icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><strong>WiFi Gratuito<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#ffffff\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#1c3621&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbAccent-Color\u00bb icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-No-Smoking\u00bb icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><strong>No Fumadores<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#262626&#8243; background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#ffffff\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbExtra-Color-1&#8243; icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-Bell2&#8243; icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong>Equipamiento bajo pedido<\/strong><\/span><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#ffffff\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#1c3621&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbAccent-Color\u00bb icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-Bathrobe\u00bb icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Ba\u00f1era <\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#ffffff\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#1c3621&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbAccent-Color\u00bb icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-Juice\u00bb icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Mini-Bar<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#1c3621&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-5-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#1c3621&#8243; background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#ffffff\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbiconsmind\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbExtra-Color-1&#8243; icon_padding=\u00bb10px\u00bb pointer_events=\u00bball\u00bb icon_iconsmind=\u00bbiconsmind-Photo\u00bb icon_size=\u00bb40&#8243;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Galer\u00eda de fotos<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_gallery type=\u00bbimage_grid\u00bb images=\u00bb338,384,386,390,378,380,388,382,352&#8243; image_grid_loading=\u00bbdefault\u00bb layout=\u00bb3&#8243; masonry_style=\u00bbtrue\u00bb item_spacing=\u00bbdefault\u00bb gallery_style=\u00bb2&#8243; load_in_animation=\u00bbnone\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#1c3621&#8243; bg_image=\u00bb80&#8243; bg_position=\u00bbright bottom\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb200&#8243; bottom_padding=\u00bb100&#8243; text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb class=\u00bbheader-inner\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":501,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-506","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Habitacion Confort - H\u00f4tel Ama Biarritz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Habitacion Confort - H\u00f4tel Ama Biarritz\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#1c3621&#8243; bg_image=\u00bb80&#8243; bg_position=\u00bbright bottom\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb200&#8243; bottom_padding=\u00bb100&#8243; text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb class=\u00bbheader-inner\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/\" \/>\n<meta property=\"og:site_name\" content=\"H\u00f4tel Ama Biarritz\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-13T15:22:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/\",\"url\":\"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/\",\"name\":\"Habitacion Confort - H\u00f4tel Ama Biarritz\",\"isPartOf\":{\"@id\":\"https:\/\/www.amahotel.fr\/#website\"},\"datePublished\":\"2020-07-23T15:03:22+00:00\",\"dateModified\":\"2025-12-13T15:22:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.amahotel.fr\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Habitaciones\",\"item\":\"https:\/\/www.amahotel.fr\/chambres\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Habitacion Confort\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.amahotel.fr\/#website\",\"url\":\"https:\/\/www.amahotel.fr\/\",\"name\":\"H\u00f4tel Ama Biarritz\",\"description\":\"Hotel au centre de Biarritz\",\"publisher\":{\"@id\":\"https:\/\/www.amahotel.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.amahotel.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.amahotel.fr\/#organization\",\"name\":\"Ama Hotel\",\"url\":\"https:\/\/www.amahotel.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.amahotel.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.amahotel.fr\/wp-content\/uploads\/2020\/03\/Ama-H\u00f4tel-Logo-Alt.png\",\"contentUrl\":\"https:\/\/www.amahotel.fr\/wp-content\/uploads\/2020\/03\/Ama-H\u00f4tel-Logo-Alt.png\",\"width\":320,\"height\":319,\"caption\":\"Ama Hotel\"},\"image\":{\"@id\":\"https:\/\/www.amahotel.fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Habitacion Confort - H\u00f4tel Ama Biarritz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/","og_locale":"es_ES","og_type":"article","og_title":"Habitacion Confort - H\u00f4tel Ama Biarritz","og_description":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#1c3621&#8243; bg_image=\u00bb80&#8243; bg_position=\u00bbright bottom\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb200&#8243; bottom_padding=\u00bb100&#8243; text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb class=\u00bbheader-inner\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb...","og_url":"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/","og_site_name":"H\u00f4tel Ama Biarritz","article_modified_time":"2025-12-13T15:22:17+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/","url":"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/","name":"Habitacion Confort - H\u00f4tel Ama Biarritz","isPartOf":{"@id":"https:\/\/www.amahotel.fr\/#website"},"datePublished":"2020-07-23T15:03:22+00:00","dateModified":"2025-12-13T15:22:17+00:00","breadcrumb":{"@id":"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.amahotel.fr\/es\/habitaciones\/habitacion-confort\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.amahotel.fr\/es\/"},{"@type":"ListItem","position":2,"name":"Habitaciones","item":"https:\/\/www.amahotel.fr\/chambres\/"},{"@type":"ListItem","position":3,"name":"Habitacion Confort"}]},{"@type":"WebSite","@id":"https:\/\/www.amahotel.fr\/#website","url":"https:\/\/www.amahotel.fr\/","name":"H\u00f4tel Ama Biarritz","description":"Hotel au centre de Biarritz","publisher":{"@id":"https:\/\/www.amahotel.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amahotel.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amahotel.fr\/#organization","name":"Ama Hotel","url":"https:\/\/www.amahotel.fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amahotel.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.amahotel.fr\/wp-content\/uploads\/2020\/03\/Ama-H\u00f4tel-Logo-Alt.png","contentUrl":"https:\/\/www.amahotel.fr\/wp-content\/uploads\/2020\/03\/Ama-H\u00f4tel-Logo-Alt.png","width":320,"height":319,"caption":"Ama Hotel"},"image":{"@id":"https:\/\/www.amahotel.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.amahotel.fr\/es\/wp-json\/wp\/v2\/pages\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amahotel.fr\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.amahotel.fr\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.amahotel.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amahotel.fr\/es\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":4,"href":"https:\/\/www.amahotel.fr\/es\/wp-json\/wp\/v2\/pages\/506\/revisions"}],"predecessor-version":[{"id":1196,"href":"https:\/\/www.amahotel.fr\/es\/wp-json\/wp\/v2\/pages\/506\/revisions\/1196"}],"up":[{"embeddable":true,"href":"https:\/\/www.amahotel.fr\/es\/wp-json\/wp\/v2\/pages\/501"}],"wp:attachment":[{"href":"https:\/\/www.amahotel.fr\/es\/wp-json\/wp\/v2\/media?parent=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}